{"id":4330,"date":"2025-01-31T17:13:01","date_gmt":"2025-01-31T16:13:01","guid":{"rendered":"https:\/\/lechappeeclose.it\/produit\/livres-hebdo\/"},"modified":"2025-10-17T18:08:36","modified_gmt":"2025-10-17T16:08:36","slug":"livres-hebdo","status":"publish","type":"product","link":"https:\/\/lechappeeclose.it\/it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/","title":{"rendered":"Les fourmis"},"content":{"rendered":"<p>Que peuvent nous envier les fourmis ? L\u2019humour, l\u2019amour, l\u2019art. Que peuvent leur envier les hommes ? L\u2019harmonie avec la nature, l\u2019absence de peur, la communication absolue.Apr\u00e8s des mill\u00e9naires d\u2019ignorance, les deux civilisations les plus \u00e9volu\u00e9es de la plan\u00e8te vont-elles enfin pouvoir se rencontrer et se comprendre ?Sans se conna\u00eetre, Julie Pinson, une \u00e9tudiante rebelle, et 103\u2019, une fourmi exploratrice, vont essayer de faire la r\u00e9volution dans leur monde respectif pour le faire \u00e9voluer.Les Fourmis \u00e9tait le livre du contact, Le Jour des fourmis le livre de la confrontation. La R\u00e9volution des fourmis est le livre de la compr\u00e9hension.Mais au-del\u00e0 du th\u00e8me des fourmis, c\u2019est une r\u00e9volution d\u2019humains, une r\u00e9volution non violente, une r\u00e9volution faite de petites touches discr\u00e8tes et d\u2019id\u00e9es nouvelles que nous propose Bernard Werber.\u00c0 la fois roman d\u2019aventures et livre initiatique, ce couronnement de l\u2019\u00e9pop\u00e9e myrm\u00e9c\u00e9enne nous convie \u00e0 entrer dans un avenir qui n\u2019est peut-\u00eatre pas seulement de la science-fiction&#8230;<\/p>","protected":false},"excerpt":{"rendered":"<p>Que peuvent nous envier les fourmis ? L\u2019humour, l\u2019amour, l\u2019art. Que peuvent leur envier les hommes ? L\u2019harmonie avec la nature, l\u2019absence de peur, la communication absolue.Apr\u00e8s des mill\u00e9naires d\u2019ignorance, les deux civilisations les plus \u00e9volu\u00e9es de la plan\u00e8te vont-elles enfin pouvoir se rencontrer et se comprendre ?Sans se conna\u00eetre, Julie Pinson, une \u00e9tudiante rebelle, [&hellip;]<\/p>","protected":false},"featured_media":4329,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[47],"product_tag":[],"class_list":["post-4330","product","type-product","status-publish","has-post-thumbnail","product_cat-polars","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les fourmis - l&#039;\u00e9chapp\u00e9e close<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/lechappeeclose.it\/it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les fourmis - l&#039;\u00e9chapp\u00e9e close\" \/>\n<meta property=\"og:description\" content=\"Que peuvent nous envier les fourmis ? L\u2019humour, l\u2019amour, l\u2019art. Que peuvent leur envier les hommes ? L\u2019harmonie avec la nature, l\u2019absence de peur, la communication absolue.Apr\u00e8s des mill\u00e9naires d\u2019ignorance, les deux civilisations les plus \u00e9volu\u00e9es de la plan\u00e8te vont-elles enfin pouvoir se rencontrer et se comprendre ?Sans se conna\u00eetre, Julie Pinson, une \u00e9tudiante rebelle, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/lechappeeclose.it\/it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/\" \/>\n<meta property=\"og:site_name\" content=\"l&#039;\u00e9chapp\u00e9e close\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T16:08:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/lechappeeclose.it\/wp-content\/uploads\/2025\/01\/Livres-hebdo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"292\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/lechappeeclose.it\\\/boutique\\\/livres\\\/litterature\\\/polars\\\/livres-hebdo\\\/\",\"url\":\"http:\\\/\\\/lechappeeclose.it\\\/boutique\\\/livres\\\/litterature\\\/polars\\\/livres-hebdo\\\/\",\"name\":\"Les fourmis - l&#039;\u00e9chapp\u00e9e close\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lechappeeclose.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/lechappeeclose.it\\\/boutique\\\/livres\\\/litterature\\\/polars\\\/livres-hebdo\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/lechappeeclose.it\\\/boutique\\\/livres\\\/litterature\\\/polars\\\/livres-hebdo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lechappeeclose.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Livres-hebdo.jpg\",\"datePublished\":\"2025-01-31T16:13:01+00:00\",\"dateModified\":\"2025-10-17T16:08:36+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/lechappeeclose.it\\\/boutique\\\/livres\\\/litterature\\\/polars\\\/livres-hebdo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/lechappeeclose.it\\\/boutique\\\/livres\\\/litterature\\\/polars\\\/livres-hebdo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/lechappeeclose.it\\\/boutique\\\/livres\\\/litterature\\\/polars\\\/livres-hebdo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lechappeeclose.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Livres-hebdo.jpg\",\"contentUrl\":\"https:\\\/\\\/lechappeeclose.it\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Livres-hebdo.jpg\",\"width\":292,\"height\":475},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/lechappeeclose.it\\\/boutique\\\/livres\\\/litterature\\\/polars\\\/livres-hebdo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lechappeeclose.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/lechappeeclose.it\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les fourmis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lechappeeclose.it\\\/#website\",\"url\":\"https:\\\/\\\/lechappeeclose.it\\\/\",\"name\":\"l&#039;\u00e9chapp\u00e9e close\",\"description\":\"la librairie fran\u00e7aise de Milan\",\"publisher\":{\"@id\":\"https:\\\/\\\/lechappeeclose.it\\\/#organization\"},\"alternateName\":\"La librairie fran\u00e7aise de Milan\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lechappeeclose.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lechappeeclose.it\\\/#organization\",\"name\":\"l&#039;\u00e9chapp\u00e9e close\",\"url\":\"https:\\\/\\\/lechappeeclose.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lechappeeclose.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lechappeeclose.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-logo-rond.png\",\"contentUrl\":\"https:\\\/\\\/lechappeeclose.it\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/cropped-logo-rond.png\",\"width\":1080,\"height\":1080,\"caption\":\"l&#039;\u00e9chapp\u00e9e close\"},\"image\":{\"@id\":\"https:\\\/\\\/lechappeeclose.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/lechappeeclose\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les fourmis - l&#039;\u00e9chapp\u00e9e close","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/lechappeeclose.it\/it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/","og_locale":"it_IT","og_type":"article","og_title":"Les fourmis - l&#039;\u00e9chapp\u00e9e close","og_description":"Que peuvent nous envier les fourmis ? L\u2019humour, l\u2019amour, l\u2019art. Que peuvent leur envier les hommes ? L\u2019harmonie avec la nature, l\u2019absence de peur, la communication absolue.Apr\u00e8s des mill\u00e9naires d\u2019ignorance, les deux civilisations les plus \u00e9volu\u00e9es de la plan\u00e8te vont-elles enfin pouvoir se rencontrer et se comprendre ?Sans se conna\u00eetre, Julie Pinson, une \u00e9tudiante rebelle, [&hellip;]","og_url":"http:\/\/lechappeeclose.it\/it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/","og_site_name":"l&#039;\u00e9chapp\u00e9e close","article_modified_time":"2025-10-17T16:08:36+00:00","og_image":[{"width":292,"height":475,"url":"http:\/\/lechappeeclose.it\/wp-content\/uploads\/2025\/01\/Livres-hebdo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/lechappeeclose.it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/","url":"http:\/\/lechappeeclose.it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/","name":"Les fourmis - l&#039;\u00e9chapp\u00e9e close","isPartOf":{"@id":"https:\/\/lechappeeclose.it\/#website"},"primaryImageOfPage":{"@id":"http:\/\/lechappeeclose.it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/#primaryimage"},"image":{"@id":"http:\/\/lechappeeclose.it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/#primaryimage"},"thumbnailUrl":"https:\/\/lechappeeclose.it\/wp-content\/uploads\/2025\/01\/Livres-hebdo.jpg","datePublished":"2025-01-31T16:13:01+00:00","dateModified":"2025-10-17T16:08:36+00:00","breadcrumb":{"@id":"http:\/\/lechappeeclose.it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/lechappeeclose.it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/lechappeeclose.it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/#primaryimage","url":"https:\/\/lechappeeclose.it\/wp-content\/uploads\/2025\/01\/Livres-hebdo.jpg","contentUrl":"https:\/\/lechappeeclose.it\/wp-content\/uploads\/2025\/01\/Livres-hebdo.jpg","width":292,"height":475},{"@type":"BreadcrumbList","@id":"http:\/\/lechappeeclose.it\/boutique\/livres\/litterature\/polars\/livres-hebdo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lechappeeclose.it\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/lechappeeclose.it\/boutique\/"},{"@type":"ListItem","position":3,"name":"Les fourmis"}]},{"@type":"WebSite","@id":"https:\/\/lechappeeclose.it\/#website","url":"https:\/\/lechappeeclose.it\/","name":"l&#039;\u00e9chapp\u00e9e close","description":"La libreria francese di Milano","publisher":{"@id":"https:\/\/lechappeeclose.it\/#organization"},"alternateName":"La librairie fran\u00e7aise de Milan","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lechappeeclose.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/lechappeeclose.it\/#organization","name":"l&#039;\u00e9chapp\u00e9e close","url":"https:\/\/lechappeeclose.it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lechappeeclose.it\/#\/schema\/logo\/image\/","url":"https:\/\/lechappeeclose.it\/wp-content\/uploads\/2025\/02\/cropped-logo-rond.png","contentUrl":"https:\/\/lechappeeclose.it\/wp-content\/uploads\/2025\/02\/cropped-logo-rond.png","width":1080,"height":1080,"caption":"l&#039;\u00e9chapp\u00e9e close"},"image":{"@id":"https:\/\/lechappeeclose.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/lechappeeclose\/"]}]}},"_links":{"self":[{"href":"https:\/\/lechappeeclose.it\/it\/wp-json\/wp\/v2\/product\/4330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lechappeeclose.it\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lechappeeclose.it\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lechappeeclose.it\/it\/wp-json\/wp\/v2\/comments?post=4330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lechappeeclose.it\/it\/wp-json\/wp\/v2\/media\/4329"}],"wp:attachment":[{"href":"https:\/\/lechappeeclose.it\/it\/wp-json\/wp\/v2\/media?parent=4330"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lechappeeclose.it\/it\/wp-json\/wp\/v2\/product_brand?post=4330"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lechappeeclose.it\/it\/wp-json\/wp\/v2\/product_cat?post=4330"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lechappeeclose.it\/it\/wp-json\/wp\/v2\/product_tag?post=4330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}